{"id":9620,"date":"2021-11-01T11:27:47","date_gmt":"2021-11-01T10:27:47","guid":{"rendered":"https:\/\/planet-randy.com\/blog\/?p=9620"},"modified":"2021-11-01T18:29:22","modified_gmt":"2021-11-01T17:29:22","slug":"zum-intersex-awareness-day","status":"publish","type":"post","link":"https:\/\/planet-randy.com\/blog\/zum-intersex-awareness-day\/","title":{"rendered":"Zum Intersex Awareness Day\u2026"},"content":{"rendered":"<p>Seit einiger Zeit wird Ende Oktober, genauer gesagt am 26.10., der sogenannte Intersex Awareness Day gefeiert. Das \u201eI\u201c ist mittlerweile auch in der Abk\u00fcrzung \u201eLGBTQI+\u201c zu finden und spielt im Leben der Community eine immer wichtigere Rolle.<\/p>\n<p>Studien zeigen, dass sich anhand von Sprache wunderbar beobachten l\u00e4sst, wie sich die Lebenseinstellung und das Leben im Allgemeinen im Laufe der Zeit ver\u00e4ndert. Dass es das \u201eI\u201c dementsprechend in die Szene Abk\u00fcrzung geschafft hat, zeigt auf, wie viele Menschen sich mittlerweile mit ihm identifizieren und dass Intersexualit\u00e4t einen Platz innerhalb der Gemeinschaft bekommen hat.<\/p>\n<p>Aktuellen Statistiken zufolge gehen Wissenschaftler davon aus, dass etwa zwei Prozent der Weltbev\u00f6lkerung intersexuell sind. Umgerechnet handelt es sich hierbei um mehr als 150 Millionen. In den meisten F\u00e4llen bemerken die Betroffenen \u00fcber einen langen Zeitraum nichts von ihrer Intersexualit\u00e4t. Erst in der Zeit der Pubert\u00e4t f\u00e4llt ihnen dann oft auf, dass Intergeschlechtlichkeit f\u00fcr sie eine gr\u00f6\u00dfere Rolle spielen k\u00f6nnte, als sie dachten.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9621\" src=\"https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay.png\" alt=\"Zum Intersex Awareness Day\u2026\" width=\"2560\" height=\"1439\" srcset=\"https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay.png 2560w, https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay-200x112.png 200w, https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay-1200x675.png 1200w, https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay-768x432.png 768w, https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay-1536x864.png 1536w, https:\/\/planet-randy.com\/blog\/wp-content\/uploads\/2021\/11\/IntersexAwarenessDay-2048x1151.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<h2>Was bedeutet intersexuell?<\/h2>\n<p>\u201e<em>Ich bin inter!<\/em>\u201c \u2013 Viele Menschen, die diesen Satz sagen, werden von ihrem Gegen\u00fcber oft ein wenig ratlos angeschaut. Wer etwas mutiger ist, hakt nach und erf\u00e4hrt mit ein wenig Gl\u00fcck \u201e<em>ganz nebenbei<\/em>\u201c, wie vielseitig die Community mittlerweile ist.<\/p>\n<p>Intersexuelle Menschen haben Geschlechtsmerkmale, die sich nicht ausschlie\u00dflich in \u201e<em>m\u00e4nnlich<\/em>\u201c bzw. \u201e<em>weiblich<\/em>\u201c einordnen lassen. Die entsprechenden (angeborenen) Variationen sind die Basis f\u00fcr die Intersexualit\u00e4t eines Menschen. M\u00f6glich w\u00e4re zum Beispiel, dass ein Mensch aussieht wie eine Frau, aber keine Geb\u00e4rmutter hat. Gleichzeitig kann es auch sein, dass einem Mann w\u00e4hrend der Pubert\u00e4t Br\u00fcste wachsen. Ein klassisches Beispiel, mit dem auch viele Menschen, die sich sonst abseits der Community bewegen, etwas anfangen k\u00f6nnen, ist der Zwitter. Dieser kommt in der Realit\u00e4t jedoch weitaus seltener vor als die anderen beiden genannten Beispiele.<\/p>\n<p>Zusatzinfo: Intersexuelle Menschen unterscheiden sich von non bin\u00e4ren Menschen durch die Tatsache, dass ihr K\u00f6rper tats\u00e4chlich Merkmale beider Geschlechter aufweist. Non bin\u00e4re Menschen m\u00f6chten sich, auch dann, wenn sie lediglich weibliche oder lediglich m\u00e4nnliche Geschlechtsmerkmale aufweisen, nicht einordnen lassen.<\/p>\n<h3>Was kann der Intersex Awareness Day bewirken?<\/h3>\n<p>Im Rahmen des Intersex Awareness Day soll darauf aufmerksam gemacht werden, dass es Millionen von Menschen gibt, die sich in geschlechtlicher Hinsicht in keine Schublade stecken lassen k\u00f6nnen. Wer sich seiner Intersexualit\u00e4t bewusst ist und Formulare ausf\u00fcllen muss, bei denen er sich zwischen \u201e<em>m\u00e4nnlich<\/em>\u201c oder \u201e<em>weiblich<\/em>\u201c entscheiden muss, kann einem enormen Druck ausgesetzt sein.<\/p>\n<p>Leider wird genau dieses Problem seitens der Gesellschaft immer noch untersch\u00e4tzt. Dabei wissen die Betroffenen selbst am besten, wie es beispielsweise ist, mit Merkmalen beider Geschlechter zu leben und sich dementsprechend keiner Seite zugeh\u00f6rig zu f\u00fchlen.<\/p>\n<p>Wahrscheinlich auch aufgrund der Aktionen der Community und wegen der Tatsache, dass sich so viele Menschen f\u00fcr mehr Diversity eingesetzt haben, hat sich die gesetzliche Lage zum Thema in Deutschland vor einigen Jahren ver\u00e4ndert.<\/p>\n<h4><strong>Wie gestaltet sich die aktuelle Lage f\u00fcr intersexuelle Menschen in Deutschland?<\/strong><\/h4>\n<p>Es ist noch nicht allzu lange her, dass entschieden wurde, dass intersexuelle Menschen in Deutschland bei \u201e<em>Geschlecht<\/em>\u201c auch ein \u201e<em>divers<\/em>\u201c angeben d\u00fcrfen. Diese Option besteht seit dem Jahr 2018. Wie viele Menschen als intersexuell auf die Welt kommen, ist nicht bekannt\u2026 unter anderem deswegen nicht, weil es letztendlich noch die Entscheidung der Eltern ist, ein bestimmtes klassisches Geschlecht in den Dokumenten vermerken zu lassen oder sich von Vornherein f\u00fcr das \u201e<em>divers<\/em>\u201c zu entscheiden. Hier ist davon auszugehen, dass viele Erziehungsberechtigte sich als junge Eltern davor scheuen, diesen Schritt zu gehen, der f\u00fcr viele gl\u00fccklicherweise selbstverst\u00e4ndlich ist und zu einem hohen Ma\u00dfe f\u00fcr Akzeptanz steht.<\/p>\n<p>&nbsp;<\/p>\n<p>Das solltest du vor der<a title=\"Die erste gemeinsame Wohnung\" href=\"https:\/\/planet-randy.com\/blog\/die-erste-gemeinsame-wohnung\/\" rel=\"bookmark\"> der ersten gemeinsame Wohnung<\/a> bedenken.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit einiger Zeit wird Ende Oktober, genauer gesagt am 26.10., der sogenannte Intersex Awareness Day gefeiert. Das \u201eI\u201c ist mittlerweile auch in der Abk\u00fcrzung \u201eLGBTQI+\u201c zu finden und spielt im Leben der Community eine immer wichtigere Rolle. Studien zeigen, dass sich anhand von Sprache wunderbar beobachten l\u00e4sst, wie sich die Lebenseinstellung und das Leben im [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-9620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-aus-der-community","wp-sticky"],"_links":{"self":[{"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/posts\/9620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/comments?post=9620"}],"version-history":[{"count":1,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/posts\/9620\/revisions"}],"predecessor-version":[{"id":9622,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/posts\/9620\/revisions\/9622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/media\/9621"}],"wp:attachment":[{"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/media?parent=9620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/categories?post=9620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/planet-randy.com\/blog\/wp-json\/wp\/v2\/tags?post=9620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}